{"id":1868,"date":"2024-05-28T02:36:04","date_gmt":"2024-05-28T02:36:04","guid":{"rendered":"https:\/\/rally-kumrovec.com\/2024\/arhiva\/?page_id=1868"},"modified":"2024-09-02T13:44:20","modified_gmt":"2024-09-02T13:44:20","slug":"media","status":"publish","type":"page","link":"https:\/\/rally-kumrovec.com\/2024\/arhiva\/13-rally-kumrovec-eng\/media\/","title":{"rendered":"Media"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1868\" class=\"elementor elementor-1868\" data-elementor-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:&quot;yes&quot;,&quot;profecient_custom_cursor_inner_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:13,&quot;sizes&quot;:&quot;&quot;},&quot;profecient_custom_cursor_inner_color&quot;:&quot;#2068F5&quot;,&quot;profecient_custom_cursor_inner_blend&quot;:&quot;normal&quot;,&quot;profecient_custom_cursor_outer_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:&quot;&quot;},&quot;profecient_custom_cursor_inner_type&quot;:&quot;none&quot;,&quot;profecient_custom_cursor_outer_color&quot;:&quot;#ffffff&quot;,&quot;profecient_custom_cursor_outer_blend&quot;:&quot;difference&quot;,&quot;profecient_custom_cursor_outer_type&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65900922 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"65900922\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6acc6490\" data-id=\"6acc6490\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-13fb72b6 profecient-mouse-effects-yes elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13fb72b6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;profecient_background_motion_effects_toggle&quot;:&quot;yes&quot;,&quot;profecient_background_motion_effects_background_width_responsive&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:105,&quot;sizes&quot;:&quot;&quot;},&quot;profecient_background_motion_effects_background_height_responsive&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:105,&quot;sizes&quot;:&quot;&quot;},&quot;profecient_background_motion_effects_position_left_responsive&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:&quot;&quot;},&quot;profecient_background_motion_effects_position_top_responsive&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:&quot;&quot;},&quot;profecient_background_mouse_effects_track_speed_responsive_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;profecient_background_motion_effects_background_width_responsive_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_background_motion_effects_background_width_responsive_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_background_motion_effects_background_height_responsive_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_background_motion_effects_background_height_responsive_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_background_motion_effects_position_left_responsive_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_background_motion_effects_position_left_responsive_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_background_motion_effects_position_top_responsive_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_background_motion_effects_position_top_responsive_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_background_mouse_effects_track_direction&quot;:&quot;direct&quot;,&quot;profecient_background_mouse_effects_track_speed_responsive&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:&quot;&quot;},&quot;profecient_background_mouse_effects_track_speed_responsive_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_background_parallax_background_color_animation_viewport&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4041e0ef\" data-id=\"4041e0ef\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-363ecd9a elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"363ecd9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">MEDIA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aed9ca0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aed9ca0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9ae6b47\" data-id=\"9ae6b47\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2652d1f5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2652d1f5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-26f977bc\" data-id=\"26f977bc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ee2fbd elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"4ee2fbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PRESS CENTER WORKING HOURS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1837f93a elementor-widget elementor-widget-text-editor\" data-id=\"1837f93a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>CONTACT\u00a0 <a href=\"mailto:press@rally-kumrovec.com\">press@rally-kumrovec.com<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e832aec elementor-widget elementor-widget-text-editor\" data-id=\"e832aec\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Multimedia Center Kumrovec<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4580dd1c elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"4580dd1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> 6.\u2060 September 2024.  |  FRIDAY  |  11:00h - 22:00h<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f700a6 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"5f700a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> 7.\u2060 September 2024.  |  SATURDAY  |  08:30h - 20:30h<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5b96c10d elementor-invisible\" data-id=\"5b96c10d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:200,&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1bdb0326 profecient-custom-cursor-yes custom-cursor__inner--type-none custom-cursor__outer--type-none elementor-widget elementor-widget-jkit_video_button\" data-id=\"1bdb0326\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:&quot;yes&quot;,&quot;profecient_custom_cursor_inner_text&quot;:&quot;Play&quot;,&quot;profecient_custom_cursor_inner_typography_content_typography_font_family&quot;:&quot;Rajdhani&quot;,&quot;profecient_custom_cursor_inner_typography_content_typography_font_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:16,&quot;sizes&quot;:[]},&quot;profecient_custom_cursor_inner_typography_content_typography_font_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:14,&quot;sizes&quot;:[]},&quot;profecient_custom_cursor_inner_typography_content_typography_font_weight&quot;:&quot;600&quot;,&quot;profecient_custom_cursor_inner_typography_content_typography_text_transform&quot;:&quot;none&quot;,&quot;profecient_custom_cursor_inner_typography_content_typography_font_style&quot;:&quot;normal&quot;,&quot;profecient_custom_cursor_inner_typography_content_typography_text_decoration&quot;:&quot;none&quot;,&quot;profecient_custom_cursor_inner_typography_content_typography_line_height&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;profecient_custom_cursor_inner_typography_content_typography_word_spacing&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_custom_cursor_inner_text_color&quot;:&quot;#FFFFFF&quot;,&quot;profecient_custom_cursor_inner_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:60,&quot;sizes&quot;:&quot;&quot;},&quot;profecient_custom_cursor_inner_color&quot;:&quot;#FF313145&quot;,&quot;profecient_custom_cursor_inner_blend&quot;:&quot;normal&quot;,&quot;profecient_custom_cursor_inner_backdrop_filter_blur&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;profecient_custom_cursor_inner_backdrop_filter_saturate&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:6,&quot;sizes&quot;:[]},&quot;profecient_custom_cursor_outer_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:&quot;&quot;},&quot;profecient_custom_cursor_inner_typography_content_typography_font_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_custom_cursor_inner_typography_content_typography_line_height_tablet&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_custom_cursor_inner_typography_content_typography_line_height_mobile&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_custom_cursor_inner_typography_content_typography_letter_spacing&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_custom_cursor_inner_typography_content_typography_letter_spacing_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_custom_cursor_inner_typography_content_typography_letter_spacing_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_custom_cursor_inner_typography_content_typography_word_spacing_tablet&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_custom_cursor_inner_typography_content_typography_word_spacing_mobile&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_custom_cursor_inner_type&quot;:&quot;none&quot;,&quot;profecient_custom_cursor_inner_backdrop_filter_brightness&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;profecient_custom_cursor_inner_backdrop_filter_contrast&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;profecient_custom_cursor_inner_backdrop_filter_grayscale&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;profecient_custom_cursor_inner_backdrop_filter_hue_rotate&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;profecient_custom_cursor_inner_backdrop_filter_opacity&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;profecient_custom_cursor_inner_backdrop_filter_sepia&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;profecient_custom_cursor_outer_color&quot;:&quot;#ffffff&quot;,&quot;profecient_custom_cursor_outer_blend&quot;:&quot;difference&quot;,&quot;profecient_custom_cursor_outer_type&quot;:&quot;none&quot;,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"jkit_video_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-video-button jeg_module___6a97ae2a3e255\"  data-autoplay=\"0\" data-loop=\"0\" data-controls=\"0\" data-type=\"youtube\" data-mute=\"0\" data-start=\"0\" data-end=\"0\"><a href=\"https:\/\/www.youtube.com\/watch?v=XVG8wYGV0oA\" class=\"jkit-video-popup-btn\" aria-label=\"video-button\"><span class=\"icon-position-before\"><i aria-hidden=\"true\" class=\"jki jki-play\"><\/i><\/span><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7a1e1092 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"7a1e1092\" data-element_type=\"section\" data-e-type=\"section\" id=\"akreditiranje\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79d34fef\" data-id=\"79d34fef\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25ab6782 elementor-widget elementor-widget-metform\" data-id=\"25ab6782\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"metform.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"mf-response-props-id-1380\" data-previous-steps-style=\"\" data-editswitchopen=\"\" data-response_type=\"alert\" data-erroricon=\"fas fa-exclamation-triangle\" data-successicon=\"fas fa-check\" data-messageposition=\"top\" class=\"   mf-scroll-top-no\">\n\t\t<div class=\"formpicker_warper formpicker_warper_editable\" data-metform-formpicker-key=\"1380\" >\n\t\t\t\t\n\t\t\t<div class=\"mf-widget-container\">\n\t\t\t\t\r\n\t\t<div\r\n\t\t\tid=\"metform-wrap-25ab6782-1380\"\r\n\t\t\tclass=\"mf-form-wrapper\"\r\n\t\t\tdata-form-id=\"1380\"\r\n\t\t\tdata-action=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-json\/metform\/v1\/entries\/insert\/1380\"\r\n\t\t\tdata-wp-nonce=\"f3fb2749d8\"\r\n\t\t\tdata-form-nonce=\"334b939691\"\r\n\t\t\tdata-quiz-summery = \"false\"\r\n\t\t\tdata-save-progress = \"false\"\r\n\t\t\tdata-form-type=\"general-form\"\r\n\t\t\tdata-stop-vertical-effect=\"\"\r\n\t\t\tdata-payment-submit-before=\"0\"\r\n\t\t\t><\/div>\r\n\r\n\r\n\t\t<!----------------------------- \r\n\t\t\t* controls_data : find the the props passed indie of data attribute\r\n\t\t\t* props.SubmitResponseMarkup : contains the markup of error or success message\r\n\t\t\t* https:\/\/developer.mozilla.org\/en-US\/docs\/Web\/JavaScript\/Reference\/Template_literals\r\n\t\t--------------------------- -->\r\n\r\n\t\t\t\t<script type=\"text\/mf\" class=\"mf-template\">\r\n\t\t\tfunction controls_data (value){\r\n\t\t\t\tlet currentWrapper = \"mf-response-props-id-1380\";\r\n\t\t\t\tlet currentEl = document.getElementById(currentWrapper);\r\n\t\t\t\t\r\n\t\t\t\treturn currentEl ? currentEl.dataset[value] : false\r\n\t\t\t}\r\n\r\n\r\n\t\t\tlet is_edit_mode = '' ? true : false;\r\n\t\t\tlet message_position = controls_data('messageposition') || 'top';\r\n\r\n\t\t\t\r\n\t\t\tlet message_successIcon = controls_data('successicon') || '';\r\n\t\t\tlet message_errorIcon = controls_data('erroricon') || '';\r\n\t\t\tlet message_editSwitch = controls_data('editswitchopen') === 'yes' ? true : false;\r\n\t\t\tlet message_proClass = controls_data('editswitchopen') === 'yes' ? 'mf_pro_activated' : '';\r\n\t\t\t\r\n\t\t\tlet is_dummy_markup = is_edit_mode && message_editSwitch ? true : false;\r\n\r\n\t\t\t\r\n\t\t\treturn html`\r\n\t\t\t\t<form\r\n\t\t\t\t\tclassName=\"metform-form-content\"\r\n\t\t\t\t\tref=${parent.formContainerRef}\r\n\t\t\t\t\tonSubmit=${ validation.handleSubmit( parent.handleFormSubmit ) }\r\n\t\t\t\t\r\n\t\t\t\t\t>\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'top' ?  props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' :  message_position === 'top' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\r\n\t\t\t\t\t<!--------------------------------------------------------\r\n\t\t\t\t\t*** IMPORTANT \/ DANGEROUS ***\r\n\t\t\t\t\t${html``} must be used as in immediate child of \"metform-form-main-wrapper\"\r\n\t\t\t\t\tclass otherwise multistep form will not run at all\r\n\t\t\t\t\t---------------------------------------------------------->\r\n\r\n\t\t\t\t\t<div className=\"metform-form-main-wrapper\" key=${'hide-form-after-submit'} ref=${parent.formRef}>\r\n\t\t\t\t\t${html`\r\n\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" key=\"2\" data-elementor-id=\"1380\" className=\"elementor elementor-1380\">\n\t\t\t\t\t\t<section className=\"elementor-section elementor-top-section elementor-element elementor-element-3c49050c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3c49050c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-505faecf\" data-id=\"505faecf\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-f875c02 elementor-widget elementor-widget-heading\" data-id=\"f875c02\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t<h3 className=\"elementor-heading-title elementor-size-default\">AKREDITIRANJE \/ ACCREDITATION<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section className=\"elementor-section elementor-inner-section elementor-element elementor-element-5f173e59 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5f173e59\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-23150c78\" data-id=\"23150c78\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-ed54ea6 elementor-widget elementor-widget-mf-text\" data-id=\"ed54ea6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;Name&quot;,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-ed54ea6\">\r\n\t\t\t\t\t${ parent.decodeEntities(`IME \/ NAME`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\r\n\t\t\t\tid=\"mf-input-text-ed54ea6\"\r\n\t\t\t\tname=\"Name\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(``) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['Name'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"Name\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2ec74617\" data-id=\"2ec74617\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-8db453a elementor-widget elementor-widget-mf-text\" data-id=\"8db453a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;Surname&quot;,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-8db453a\">\r\n\t\t\t\t\t${ parent.decodeEntities(`PREZIME \/ SURNAME`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\r\n\t\t\t\tid=\"mf-input-text-8db453a\"\r\n\t\t\t\tname=\"Surname\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(``) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['Surname'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"Surname\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section className=\"elementor-section elementor-inner-section elementor-element elementor-element-6da24b58 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6da24b58\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2de337f4\" data-id=\"2de337f4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-d95300b elementor-widget elementor-widget-mf-text\" data-id=\"d95300b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;Office&quot;,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-d95300b\">\r\n\t\t\t\t\t${ parent.decodeEntities(`Redakcija \/ Editorial office`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\r\n\t\t\t\tid=\"mf-input-text-d95300b\"\r\n\t\t\t\tname=\"Office\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(``) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['Office'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"Office\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-34de38a9 elementor-widget elementor-widget-mf-email\" data-id=\"34de38a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;Email&quot;,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"mf-email.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-email-34de38a9\">\r\n\t\t\t\t\t${ parent.decodeEntities(`Email Adresa \/ Address`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input \r\n\t\t\t\ttype=\"email\" \r\n\t\t\t\t \r\n\t\t\t\tdefaultValue=\"\" \r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\" \r\n\t\t\t\tid=\"mf-input-email-34de38a9\" \r\n\t\t\t\tname=\"Email\" \r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(``) } \" \r\n\t\t\t\t \r\n\t\t\t\tonBlur=${parent.handleChange} onFocus=${parent.handleChange} aria-invalid=${validation.errors['Email'] ? 'true' : 'false' } \r\n\t\t\t\tref=${el=> parent.activateValidation({\"message\":\"This field is required.\",\"emailMessage\":\"Please enter a valid Email address\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t<${validation.ErrorMessage} \r\n\t\t\t\terrors=${validation.errors} \r\n\t\t\t\tname=\"Email\" \r\n\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-d8e3e8a elementor-widget elementor-widget-mf-text\" data-id=\"d8e3e8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;Address&quot;,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-d8e3e8a\">\r\n\t\t\t\t\t${ parent.decodeEntities(`ADRESA \/ ADDRESS`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\r\n\t\t\t\tid=\"mf-input-text-d8e3e8a\"\r\n\t\t\t\tname=\"Address\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(``) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['Address'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"Address\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-34393d39 elementor-widget elementor-widget-mf-telephone\" data-id=\"34393d39\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;Phone&quot;,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"mf-telephone.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-telephone-34393d39\">\n\t\t\t\t\t${ parent.decodeEntities(`Broj telefona \/ Phone Number`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\n\t\t\t\t<\/label>\n\t\t\t\n\t\t\t<input\n\t\t\t\ttype=\"tel\"\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\n\t\t\t\tid=\"mf-input-telephone-34393d39\" \n\t\t\t\tname=\"Phone\"\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(``) } \"\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\n\t\t\t\t\taria-invalid=${validation.errors['Phone'] ? 'true' : 'false'}\n\t\t\t\t\tref=${el => parent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\n\t\t\t\t\t\t\t\t\/>\n\t\t\t\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\n\t\t\t\t\terrors=${validation.errors}\n\t\t\t\t\tname=\"Phone\"\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\n\t\t\t\t\t\/>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section className=\"elementor-section elementor-inner-section elementor-element elementor-element-1d7af98b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1d7af98b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-63ceb0c0\" data-id=\"63ceb0c0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-7718f6ba elementor-widget elementor-widget-mf-checkbox\" data-id=\"7718f6ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-race&quot;,&quot;mf_input_list&quot;:[{&quot;mf_input_option_text&quot;:&quot;Novine \\\/ Newspaper&quot;,&quot;mf_input_option_value&quot;:&quot;newspaper&quot;,&quot;_id&quot;:&quot;5db4c3d&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Radio&quot;,&quot;mf_input_option_value&quot;:&quot;radio&quot;,&quot;_id&quot;:&quot;7db8a4b&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Internet&quot;,&quot;mf_input_option_value&quot;:&quot;internet&quot;,&quot;_id&quot;:&quot;669ba08&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Television&quot;,&quot;mf_input_option_value&quot;:&quot;tv&quot;,&quot;_id&quot;:&quot;f19aebc&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Fotoreporter \\\/ Photoreporter&quot;,&quot;mf_input_option_value&quot;:&quot;photoreporter&quot;,&quot;_id&quot;:&quot;36c88d6&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;Snimatelj \\\/ Cameraman&quot;,&quot;mf_input_option_value&quot;:&quot;cameraman&quot;,&quot;_id&quot;:&quot;323873e&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;}],&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"mf-checkbox.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-checkbox-7718f6ba\">\r\n\t\t\t\t\t${ parent.decodeEntities(`Ozna\u010di \/ mark`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<div \r\n\t\t\t\t\t\t\t\t\tref=${el => parent.handleCheckbox(el, 'onLoad')}\r\n\t\t\t\t\t\t\t\t\tclassName=\"mf-checkbox multi-option-input-type\"\r\n\t\t\t\t\tid=\"mf-input-checkbox-7718f6ba\">\r\n\t\t\t\t\t\t\t\t\t<div className=\"mf-checkbox-option \">\r\n\t\t\t\t\t\t<label>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input type=\"checkbox\"\r\n\t\t\t\t\t\t\t\tclassName=\"mf-input mf-checkbox-input mf-conditional-input\"\r\n\t\t\t\t\t\t\t\tname=\"mf-race\"\r\n\t\t\t\t\t\t\t\tvalue=\"newspaper\"\r\n\t\t\t\t\t\t\t\tdefaultChecked=\"\"\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tonInput=${ el =>  parent.handleCheckbox(el.target, 'onClick') }\r\n\t\t\t\t\t\t\t\t\taria-invalid=${validation.errors['mf-race'] ? 'true' : 'false'}\r\n\t\t\t\t\t\t\t\t\tref=${el => {\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\/>\r\n\t\t\t\t\t\t\t<span>\r\n\t\t\t\t\t\t\t\t${ parent.decodeEntities(`Novine \/ Newspaper`) } \t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t<\/label>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div className=\"mf-checkbox-option \">\r\n\t\t\t\t\t\t<label>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input type=\"checkbox\"\r\n\t\t\t\t\t\t\t\tclassName=\"mf-input mf-checkbox-input mf-conditional-input\"\r\n\t\t\t\t\t\t\t\tname=\"mf-race\"\r\n\t\t\t\t\t\t\t\tvalue=\"radio\"\r\n\t\t\t\t\t\t\t\tdefaultChecked=\"\"\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tonInput=${ el =>  parent.handleCheckbox(el.target, 'onClick') }\r\n\t\t\t\t\t\t\t\t\taria-invalid=${validation.errors['mf-race'] ? 'true' : 'false'}\r\n\t\t\t\t\t\t\t\t\tref=${el => {\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\/>\r\n\t\t\t\t\t\t\t<span>\r\n\t\t\t\t\t\t\t\t${ parent.decodeEntities(`Radio`) } \t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t<\/label>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div className=\"mf-checkbox-option \">\r\n\t\t\t\t\t\t<label>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input type=\"checkbox\"\r\n\t\t\t\t\t\t\t\tclassName=\"mf-input mf-checkbox-input mf-conditional-input\"\r\n\t\t\t\t\t\t\t\tname=\"mf-race\"\r\n\t\t\t\t\t\t\t\tvalue=\"internet\"\r\n\t\t\t\t\t\t\t\tdefaultChecked=\"\"\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tonInput=${ el =>  parent.handleCheckbox(el.target, 'onClick') }\r\n\t\t\t\t\t\t\t\t\taria-invalid=${validation.errors['mf-race'] ? 'true' : 'false'}\r\n\t\t\t\t\t\t\t\t\tref=${el => {\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\/>\r\n\t\t\t\t\t\t\t<span>\r\n\t\t\t\t\t\t\t\t${ parent.decodeEntities(`Internet`) } \t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t<\/label>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div className=\"mf-checkbox-option \">\r\n\t\t\t\t\t\t<label>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input type=\"checkbox\"\r\n\t\t\t\t\t\t\t\tclassName=\"mf-input mf-checkbox-input mf-conditional-input\"\r\n\t\t\t\t\t\t\t\tname=\"mf-race\"\r\n\t\t\t\t\t\t\t\tvalue=\"tv\"\r\n\t\t\t\t\t\t\t\tdefaultChecked=\"\"\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tonInput=${ el =>  parent.handleCheckbox(el.target, 'onClick') }\r\n\t\t\t\t\t\t\t\t\taria-invalid=${validation.errors['mf-race'] ? 'true' : 'false'}\r\n\t\t\t\t\t\t\t\t\tref=${el => {\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\/>\r\n\t\t\t\t\t\t\t<span>\r\n\t\t\t\t\t\t\t\t${ parent.decodeEntities(`Television`) } \t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t<\/label>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div className=\"mf-checkbox-option \">\r\n\t\t\t\t\t\t<label>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input type=\"checkbox\"\r\n\t\t\t\t\t\t\t\tclassName=\"mf-input mf-checkbox-input mf-conditional-input\"\r\n\t\t\t\t\t\t\t\tname=\"mf-race\"\r\n\t\t\t\t\t\t\t\tvalue=\"photoreporter\"\r\n\t\t\t\t\t\t\t\tdefaultChecked=\"\"\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tonInput=${ el =>  parent.handleCheckbox(el.target, 'onClick') }\r\n\t\t\t\t\t\t\t\t\taria-invalid=${validation.errors['mf-race'] ? 'true' : 'false'}\r\n\t\t\t\t\t\t\t\t\tref=${el => {\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\/>\r\n\t\t\t\t\t\t\t<span>\r\n\t\t\t\t\t\t\t\t${ parent.decodeEntities(`Fotoreporter \/ Photoreporter`) } \t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t<\/label>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div className=\"mf-checkbox-option \">\r\n\t\t\t\t\t\t<label>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input type=\"checkbox\"\r\n\t\t\t\t\t\t\t\tclassName=\"mf-input mf-checkbox-input mf-conditional-input\"\r\n\t\t\t\t\t\t\t\tname=\"mf-race\"\r\n\t\t\t\t\t\t\t\tvalue=\"cameraman\"\r\n\t\t\t\t\t\t\t\tdefaultChecked=\"\"\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tonInput=${ el =>  parent.handleCheckbox(el.target, 'onClick') }\r\n\t\t\t\t\t\t\t\t\taria-invalid=${validation.errors['mf-race'] ? 'true' : 'false'}\r\n\t\t\t\t\t\t\t\t\tref=${el => {\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\/>\r\n\t\t\t\t\t\t\t<span>\r\n\t\t\t\t\t\t\t\t${ parent.decodeEntities(`Snimatelj \/ Cameraman`) } \t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t<\/label>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<input type=\"hidden\" name=\"mf-race\" value=\"\" \/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-race\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section className=\"elementor-section elementor-inner-section elementor-element elementor-element-7f439f39 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7f439f39\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1a1acfd2\" data-id=\"1a1acfd2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-4056c99 elementor-widget elementor-widget-heading\" data-id=\"4056c99\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t<h3 className=\"elementor-heading-title elementor-size-default\">Organizator zadr\u017eava pravo odbiti zahtjev za izdavanje akreditacije i bluzona, kao i njihovo oduzimanje u slu\u010daju nepo\u0161tivanja propisanih upozorenja i bilo kakvog nedoli\u010dnog pona\u0161anja na natjecanju.\nOrganizator zadr\u017eava pravo diskrecijskom odlukom odobriti izdavanje bluzona predstavniku koji ne ispunjava uvjet za isto. Potvrdom ovog obrasca potvr\u0111ujem da sam pro\u010ditao i razumio gore navedene informacije. Potvr\u0111ujem da u ovom natjecanju sudjelujem na vlastitu odgovornost!<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-0bdda05 elementor-widget elementor-widget-heading\" data-id=\"0bdda05\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t<h3 className=\"elementor-heading-title elementor-size-default\"> The organizer has right to refuse the request for the accreditation and blouson, as well as to confiscate them in case of non-compliance with the prescribed warnings and any inappropriate behavior at the competition. Accepting this form, I confirm that I have read and understood the above information. I confirm that I participate in this competition at my own risk!\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-603ba42 elementor-widget elementor-widget-mf-checkbox\" data-id=\"603ba42\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;Safety&quot;,&quot;mf_input_list&quot;:[{&quot;mf_input_option_text&quot;:&quot;I agree \\\/ Sla\\u017eem se&quot;,&quot;mf_input_option_value&quot;:&quot;privola&quot;,&quot;_id&quot;:&quot;5db4c3d&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;}],&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"mf-checkbox.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-checkbox-603ba42\">\r\n\t\t\t\t\t${ parent.decodeEntities(`Sigurnost \/ Safety`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<div \r\n\t\t\t\t\t\t\t\t\tref=${el => parent.handleCheckbox(el, 'onLoad')}\r\n\t\t\t\t\t\t\t\t\tclassName=\"mf-checkbox multi-option-input-type\"\r\n\t\t\t\t\tid=\"mf-input-checkbox-603ba42\">\r\n\t\t\t\t\t\t\t\t\t<div className=\"mf-checkbox-option \">\r\n\t\t\t\t\t\t<label>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input type=\"checkbox\"\r\n\t\t\t\t\t\t\t\tclassName=\"mf-input mf-checkbox-input mf-conditional-input\"\r\n\t\t\t\t\t\t\t\tname=\"Safety\"\r\n\t\t\t\t\t\t\t\tvalue=\"privola\"\r\n\t\t\t\t\t\t\t\tdefaultChecked=\"\"\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tonInput=${ el =>  parent.handleCheckbox(el.target, 'onClick') }\r\n\t\t\t\t\t\t\t\t\taria-invalid=${validation.errors['Safety'] ? 'true' : 'false'}\r\n\t\t\t\t\t\t\t\t\tref=${el => {\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\/>\r\n\t\t\t\t\t\t\t<span>\r\n\t\t\t\t\t\t\t\t${ parent.decodeEntities(`I agree \/ Sla\u017eem se`) } \t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t<\/label>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<input type=\"hidden\" name=\"Safety\" value=\"\" \/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"Safety\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-011766c elementor-widget elementor-widget-heading\" data-id=\"011766c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t<h3 className=\"elementor-heading-title elementor-size-default\">GDPR i obrada podataka\nPrihva\u0107anjem privole, vlastoru\u010dnim potpisom Obrasca za akreditaciju na \u201c13. MOTUL Rally Kumrovec 2024.\u201d, odnosno ispunjavanjem i slanjem e-Obrasca, jam\u010dim da su svi navedeni podaci istiniti te da prihva\u0107am uvjete koji se odnose na moje sudjelovanje na ovom natjecanju. Prihva\u0107anjem privole i vlastoru\u010dnim potpisom dobrovoljno i nedvosmisleno dajem svoj pristanak za prikupljanje i obradu svih navedenih osobnih podataka u svrhu provo\u0111enja predmetnog sportskog natjecanja.\u200b Organizator zadr\u017eava pravo diskrecijskom odlukom odobriti izdavanje bluzona predstavniku koji ne ispunjava uvjet za isto. Potvrdom ovog obrasca potvr\u0111ujem da sam pro\u010ditao i razumio gore navedene informacije. Potvr\u0111ujem da u ovom natjecanju sudjelujem na vlastitu odgovornost!<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-d1b8c52 elementor-widget elementor-widget-heading\" data-id=\"d1b8c52\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t<h3 className=\"elementor-heading-title elementor-size-default\">GDPR and data processing\nBy accepting the consent, by personally signing the Accreditation Form on \"13. MOTUL Rally Kumrovec 2024\", i.e. by filling out and sending the e-Form, I guarantee that all the given information is true and that I accept the conditions related to my participation in this competition. By accepting consent and signing with my own hand, I voluntarily and unequivocally give my consent to the collection and processing of all mentioned personal data for the purpose of conducting the sports competition in question. The organizer reserves the right to issue a blouson to a representative who does not meet the conditions for the same at its discretion. By confirming this form, I confirm that I have read and understood the above information. I confirm that I participate in this competition at my own risk!<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-56a61f9 elementor-widget elementor-widget-mf-checkbox\" data-id=\"56a61f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;GDPR&quot;,&quot;mf_input_list&quot;:[{&quot;mf_input_option_text&quot;:&quot;I agree \\\/ Sla\\u017eem se&quot;,&quot;mf_input_option_value&quot;:&quot;privola&quot;,&quot;_id&quot;:&quot;5db4c3d&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;}],&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"mf-checkbox.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-checkbox-56a61f9\">\r\n\t\t\t\t\t${ parent.decodeEntities(`GDPR i obrada podataka \/ GDPR and data management`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<div \r\n\t\t\t\t\t\t\t\t\tref=${el => parent.handleCheckbox(el, 'onLoad')}\r\n\t\t\t\t\t\t\t\t\tclassName=\"mf-checkbox multi-option-input-type\"\r\n\t\t\t\t\tid=\"mf-input-checkbox-56a61f9\">\r\n\t\t\t\t\t\t\t\t\t<div className=\"mf-checkbox-option \">\r\n\t\t\t\t\t\t<label>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input type=\"checkbox\"\r\n\t\t\t\t\t\t\t\tclassName=\"mf-input mf-checkbox-input mf-conditional-input\"\r\n\t\t\t\t\t\t\t\tname=\"GDPR\"\r\n\t\t\t\t\t\t\t\tvalue=\"privola\"\r\n\t\t\t\t\t\t\t\tdefaultChecked=\"\"\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tonInput=${ el =>  parent.handleCheckbox(el.target, 'onClick') }\r\n\t\t\t\t\t\t\t\t\taria-invalid=${validation.errors['GDPR'] ? 'true' : 'false'}\r\n\t\t\t\t\t\t\t\t\tref=${el => {\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\/>\r\n\t\t\t\t\t\t\t<span>\r\n\t\t\t\t\t\t\t\t${ parent.decodeEntities(`I agree \/ Sla\u017eem se`) } \t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t<\/label>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<input type=\"hidden\" name=\"GDPR\" value=\"\" \/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"GDPR\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-4c340c1a elementor-widget__width-auto mf-btn--mobile-center elementor-widget elementor-widget-mf-button\" data-id=\"4c340c1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"mf-button.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"mf-hidden-input-name\" className=\"mf_hidden_input_class\" value=\"mf_hidden_input_value\" ref=${parent.setDefault} \/>\r\n\t\t\t\t\t\t<div className=\"mf-btn-wraper mf-conditional-input\" data-mf-form-conditional-logic-requirement=\"\">\r\n\t\t\t\t\t\t\t<button type=\"submit\" className=\"metform-btn metform-submit-btn \" id=\"\">\r\n\t\t\t\t\t<span>${ parent.decodeEntities(`PO\u0160ALJI PRIJAVU \/ SEND AN APPLICATION`) } <\/span>\r\n\t\t\t\t<\/button>\r\n\t\t\t        <\/div>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t`}\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'bottom' ? props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' : message_position === 'bottom' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\t\t\t\t\r\n\t\t\t\t<\/form>\r\n\t\t\t`\r\n\t\t<\/script>\r\n\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a98e436 profecient-parallax-yes elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a98e436\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;profecient_parallax_effects_transition_property&quot;:&quot;transform, filter&quot;,&quot;profecient_parallax_effects_transition_duration&quot;:&quot;800ms&quot;,&quot;profecient_parallax_effects_transition_easing&quot;:&quot;ease-out&quot;,&quot;profecient_parallax_effects_rotate_x_css_unit&quot;:&quot;deg&quot;,&quot;profecient_parallax_effects_toggle&quot;:&quot;yes&quot;,&quot;profecient_parallax_effects_perspective_css_unit&quot;:&quot;px&quot;,&quot;profecient_parallax_effects_perspective_popover_start&quot;:&quot;yes&quot;,&quot;profecient_parallax_effects_perspective_start_responsive&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1000,&quot;sizes&quot;:&quot;&quot;},&quot;profecient_parallax_effects_perspective_end_responsive&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1000,&quot;sizes&quot;:&quot;&quot;},&quot;profecient_parallax_effects_perspective_animation_viewport&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:30}},&quot;profecient_parallax_effects_rotate_x_popover_start&quot;:&quot;yes&quot;,&quot;profecient_parallax_effects_rotate_x_start_responsive&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:8,&quot;sizes&quot;:&quot;&quot;},&quot;profecient_parallax_effects_rotate_x_animation_viewport&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:30}},&quot;profecient_parallax_effects_transition_popover_start&quot;:&quot;yes&quot;,&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_perspective_start_responsive_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_parallax_effects_perspective_start_responsive_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_parallax_effects_perspective_end_responsive_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_parallax_effects_perspective_end_responsive_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_parallax_effects_perspective_relative_animation_viewport&quot;:&quot;element&quot;,&quot;profecient_parallax_effects_rotate_x_start_responsive_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_parallax_effects_rotate_x_start_responsive_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_parallax_effects_rotate_x_end_responsive&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:&quot;&quot;},&quot;profecient_parallax_effects_rotate_x_end_responsive_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_parallax_effects_rotate_x_end_responsive_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;profecient_parallax_effects_rotate_x_relative_animation_viewport&quot;:&quot;element&quot;,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ffeac51\" data-id=\"ffeac51\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-534b149 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"534b149\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-018b9a8\" data-id=\"018b9a8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51a4b42 elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"51a4b42\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>SPONSORS<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d65c230 elementor-widget elementor-widget-jkit_client_logo\" data-id=\"d65c230\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"jkit_client_logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-client-logo arrow-bottom-middle jeg_module__1_6a97ae2a573d6\"  data-id=\"jeg_module__1_6a97ae2a573d6\" data-settings=\"{&quot;autoplay&quot;:true,&quot;autoplay_speed&quot;:2000,&quot;autoplay_hover_pause&quot;:false,&quot;show_navigation&quot;:false,&quot;navigation_left&quot;:&quot;&lt;span&gt;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-angle-left\\&quot; viewBox=\\&quot;0 0 256 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.7 239l136-136c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9L127.9 256l96.4 96.4c9.4 9.4 9.4 24.6 0 33.9L201.7 409c-9.4 9.4-24.6 9.4-33.9 0l-136-136c-9.5-9.4-9.5-24.6-.1-34z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&lt;\\\/span&gt;&quot;,&quot;navigation_right&quot;:&quot;&lt;span&gt;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-angle-right\\&quot; viewBox=\\&quot;0 0 256 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&lt;\\\/span&gt;&quot;,&quot;show_dots&quot;:false,&quot;arrow_position&quot;:&quot;bottom&quot;,&quot;responsive&quot;:{&quot;desktop&quot;:{&quot;items&quot;:&quot;5&quot;,&quot;margin&quot;:&quot;60&quot;,&quot;breakpoint&quot;:1025},&quot;tablet&quot;:{&quot;items&quot;:&quot;4&quot;,&quot;margin&quot;:&quot;40&quot;,&quot;breakpoint&quot;:768},&quot;mobile&quot;:{&quot;items&quot;:&quot;2&quot;,&quot;margin&quot;:20,&quot;breakpoint&quot;:0}}}\"><div class=\"client-list\"><div class=\"client-track\"><div class=\"client-slider item \"><div class=\"image-list\"><a href=\"https:\/\/www.motul.com\/hr\/hr\" class=\"client-logo-link\"><div class=\"content-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"657\" height=\"276\" src=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_8.png\" class=\"main-image\" alt=\"Title\" srcset=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_8.png 657w, https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_8-300x126.png 300w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/div><\/a><\/div><\/div><div class=\"client-slider item \"><div class=\"image-list\"><a href=\"https:\/\/tehnolub.com\/\" class=\"client-logo-link\"><div class=\"content-image\"><img decoding=\"async\" width=\"657\" height=\"276\" src=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_9.png\" class=\"main-image\" alt=\"Title\" srcset=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_9.png 657w, https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_9-300x126.png 300w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/div><\/a><\/div><\/div><div class=\"client-slider item \"><div class=\"image-list\"><a href=\"https:\/\/www.terme-tuhelj.hr\/\" class=\"client-logo-link\"><div class=\"content-image\"><img decoding=\"async\" width=\"657\" height=\"276\" src=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_10.png\" class=\"main-image\" alt=\"Title\" srcset=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_10.png 657w, https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_10-300x126.png 300w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/div><\/a><\/div><\/div><div class=\"client-slider item \"><div class=\"image-list\"><a href=\"https:\/\/www.kamgrad.hr\/hr\/\" class=\"client-logo-link\"><div class=\"content-image\"><img loading=\"lazy\" decoding=\"async\" width=\"657\" height=\"276\" src=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_11.png\" class=\"main-image\" alt=\"Title\" srcset=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_11.png 657w, https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_11-300x126.png 300w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/div><\/a><\/div><\/div><div class=\"client-slider item \"><div class=\"image-list\"><a href=\"https:\/\/topla.hr\/\" class=\"client-logo-link\"><div class=\"content-image\"><img loading=\"lazy\" decoding=\"async\" width=\"657\" height=\"276\" src=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_12.png\" class=\"main-image\" alt=\"Title\" srcset=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_12.png 657w, https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_12-300x126.png 300w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/div><\/a><\/div><\/div><div class=\"client-slider item \"><div class=\"image-list\"><a href=\"https:\/\/www.stefan.hr\/\" class=\"client-logo-link\"><div class=\"content-image\"><img loading=\"lazy\" decoding=\"async\" width=\"657\" height=\"276\" src=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_13.png\" class=\"main-image\" alt=\"Title\" srcset=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_13.png 657w, https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_13-300x126.png 300w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/div><\/a><\/div><\/div><div class=\"client-slider item \"><div class=\"image-list\"><a href=\"https:\/\/heli-space.com\/\" class=\"client-logo-link\"><div class=\"content-image\"><img loading=\"lazy\" decoding=\"async\" width=\"657\" height=\"276\" src=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_14.png\" class=\"main-image\" alt=\"Title\" srcset=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_14.png 657w, https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_14-300x126.png 300w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/div><\/a><\/div><\/div><div class=\"client-slider item \"><div class=\"image-list\"><a href=\"https:\/\/arskopija.hr\/\" class=\"client-logo-link\"><div class=\"content-image\"><img loading=\"lazy\" decoding=\"async\" width=\"657\" height=\"276\" src=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_18.png\" class=\"main-image\" alt=\"Title\" srcset=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_18.png 657w, https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_18-300x126.png 300w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/div><\/a><\/div><\/div><div class=\"client-slider item \"><div class=\"image-list\"><a href=\"https:\/\/www.mireofleet.com\/\" class=\"client-logo-link\"><div class=\"content-image\"><img loading=\"lazy\" decoding=\"async\" width=\"657\" height=\"276\" src=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_16.png\" class=\"main-image\" alt=\"Title\" srcset=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_16.png 657w, https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_16-300x126.png 300w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/div><\/a><\/div><\/div><div class=\"client-slider item \"><div class=\"image-list\"><a href=\"https:\/\/web.facebook.com\/viaadlitus\/?_rdc=1&amp;_rdr\" class=\"client-logo-link\"><div class=\"content-image\"><img loading=\"lazy\" decoding=\"async\" width=\"657\" height=\"276\" src=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_17.png\" class=\"main-image\" alt=\"Title\" srcset=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_17.png 657w, https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_17-300x126.png 300w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/div><\/a><\/div><\/div><div class=\"client-slider item \"><div class=\"image-list\"><a href=\"https:\/\/www.veronika.hr\/\" class=\"client-logo-link\"><div class=\"content-image\"><img loading=\"lazy\" decoding=\"async\" width=\"657\" height=\"276\" src=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_25.png\" class=\"main-image\" alt=\"Title\" srcset=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_25.png 657w, https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_25-300x126.png 300w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/div><\/a><\/div><\/div><div class=\"client-slider item \"><div class=\"image-list\"><a href=\"https:\/\/www.in-time.hr\/\" class=\"client-logo-link\"><div class=\"content-image\"><img loading=\"lazy\" decoding=\"async\" width=\"657\" height=\"276\" src=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_26.png\" class=\"main-image\" alt=\"Title\" srcset=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_26.png 657w, https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_26-300x126.png 300w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/div><\/a><\/div><\/div><div class=\"client-slider item \"><div class=\"image-list\"><a href=\"https:\/\/radio-stubica.hr\/\" class=\"client-logo-link\"><div class=\"content-image\"><img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"73\" src=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/09\/Radio-Stubica-Logo1.png\" class=\"main-image\" alt=\"Title\" \/><\/div><\/a><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-537b0ba elementor-widget elementor-widget-jkit_client_logo\" data-id=\"537b0ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"jkit_client_logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-client-logo arrow-bottom-middle jeg_module__2_6a97ae2a5abfa\"  data-id=\"jeg_module__2_6a97ae2a5abfa\" data-settings=\"{&quot;autoplay&quot;:true,&quot;autoplay_speed&quot;:2000,&quot;autoplay_hover_pause&quot;:false,&quot;show_navigation&quot;:false,&quot;navigation_left&quot;:&quot;&lt;span&gt;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-angle-left\\&quot; viewBox=\\&quot;0 0 256 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.7 239l136-136c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9L127.9 256l96.4 96.4c9.4 9.4 9.4 24.6 0 33.9L201.7 409c-9.4 9.4-24.6 9.4-33.9 0l-136-136c-9.5-9.4-9.5-24.6-.1-34z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&lt;\\\/span&gt;&quot;,&quot;navigation_right&quot;:&quot;&lt;span&gt;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-angle-right\\&quot; viewBox=\\&quot;0 0 256 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&lt;\\\/span&gt;&quot;,&quot;show_dots&quot;:false,&quot;arrow_position&quot;:&quot;bottom&quot;,&quot;responsive&quot;:{&quot;desktop&quot;:{&quot;items&quot;:&quot;5&quot;,&quot;margin&quot;:&quot;60&quot;,&quot;breakpoint&quot;:1025},&quot;tablet&quot;:{&quot;items&quot;:&quot;4&quot;,&quot;margin&quot;:&quot;40&quot;,&quot;breakpoint&quot;:768},&quot;mobile&quot;:{&quot;items&quot;:&quot;2&quot;,&quot;margin&quot;:20,&quot;breakpoint&quot;:0}}}\"><div class=\"client-list\"><div class=\"client-track\"><div class=\"client-slider item \"><div class=\"image-list\"><a href=\"https:\/\/www.setcor.com\/\" class=\"client-logo-link\"><div class=\"content-image\"><img loading=\"lazy\" decoding=\"async\" width=\"657\" height=\"276\" src=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_19-1.png\" class=\"main-image\" alt=\"Title\" srcset=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_19-1.png 657w, https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_19-1-300x126.png 300w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/div><\/a><\/div><\/div><div class=\"client-slider item \"><div class=\"image-list\"><a href=\"https:\/\/www.suzuki-antarescentar.hr\/\" class=\"client-logo-link\"><div class=\"content-image\"><img loading=\"lazy\" decoding=\"async\" width=\"657\" height=\"276\" src=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_20.png\" class=\"main-image\" alt=\"Title\" srcset=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_20.png 657w, https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_20-300x126.png 300w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/div><\/a><\/div><\/div><div class=\"client-slider item \"><div class=\"image-list\"><a href=\"https:\/\/www.gp1.hr\/\" class=\"client-logo-link\"><div class=\"content-image\"><img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"73\" src=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/08\/GP1-Logo.png\" class=\"main-image\" alt=\"Title\" \/><\/div><\/a><\/div><\/div><div class=\"client-slider item \"><div class=\"image-list\"><a href=\"https:\/\/www.bindjo.hr\/\" class=\"client-logo-link\"><div class=\"content-image\"><img loading=\"lazy\" decoding=\"async\" width=\"657\" height=\"276\" src=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_21.png\" class=\"main-image\" alt=\"Title\" srcset=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_21.png 657w, https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_21-300x126.png 300w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/div><\/a><\/div><\/div><div class=\"client-slider item \"><div class=\"image-list\"><a href=\"https:\/\/www.ksu.hr\/\" class=\"client-logo-link\"><div class=\"content-image\"><img loading=\"lazy\" decoding=\"async\" width=\"657\" height=\"276\" src=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_22.png\" class=\"main-image\" alt=\"Title\" srcset=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_22.png 657w, https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_22-300x126.png 300w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/div><\/a><\/div><\/div><div class=\"client-slider item \"><div class=\"image-list\"><a href=\"https:\/\/www.tokic.hr\/\" class=\"client-logo-link\"><div class=\"content-image\"><img loading=\"lazy\" decoding=\"async\" width=\"657\" height=\"276\" src=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_23.png\" class=\"main-image\" alt=\"Title\" srcset=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_23.png 657w, https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_23-300x126.png 300w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/div><\/a><\/div><\/div><div class=\"client-slider item \"><div class=\"image-list\"><a href=\"https:\/\/www.erstebank.hr\/hr\/gradjanstvo\" class=\"client-logo-link\"><div class=\"content-image\"><img loading=\"lazy\" decoding=\"async\" width=\"657\" height=\"276\" src=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/07\/Supersport.png\" class=\"main-image\" alt=\"Title\" srcset=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/07\/Supersport.png 657w, https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/07\/Supersport-300x126.png 300w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/div><\/a><\/div><\/div><div class=\"client-slider item \"><div class=\"image-list\"><a href=\"https:\/\/www.milgon.hu\/\" class=\"client-logo-link\"><div class=\"content-image\"><img loading=\"lazy\" decoding=\"async\" width=\"657\" height=\"276\" src=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_15.png\" class=\"main-image\" alt=\"Title\" srcset=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_15.png 657w, https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_15-300x126.png 300w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/div><\/a><\/div><\/div><div class=\"client-slider item \"><div class=\"image-list\"><a href=\"https:\/\/www.mhz.hr\/\" class=\"client-logo-link\"><div class=\"content-image\"><img loading=\"lazy\" decoding=\"async\" width=\"657\" height=\"276\" src=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_27.png\" class=\"main-image\" alt=\"Title\" srcset=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_27.png 657w, https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_27-300x126.png 300w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/div><\/a><\/div><\/div><div class=\"client-slider item \"><div class=\"image-list\"><a href=\"https:\/\/www.arto.com.hr\/\" class=\"client-logo-link\"><div class=\"content-image\"><img loading=\"lazy\" decoding=\"async\" width=\"657\" height=\"276\" src=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_28.png\" class=\"main-image\" alt=\"Title\" srcset=\"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_28.png 657w, https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-content\/uploads\/2024\/05\/Logo_28-300x126.png 300w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/><\/div><\/a><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>MEDIA PRESS CENTER WORKING HOURS CONTACT\u00a0 press@rally-kumrovec.com Multimedia Center Kumrovec 6.\u2060 September 2024. | FRIDAY | 11:00h &#8211; 22:00h 7.\u2060 September 2024. | SATURDAY | 08:30h &#8211; 20:30h SPONSORS<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1804,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-1868","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-json\/wp\/v2\/pages\/1868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-json\/wp\/v2\/comments?post=1868"}],"version-history":[{"count":22,"href":"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-json\/wp\/v2\/pages\/1868\/revisions"}],"predecessor-version":[{"id":3019,"href":"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-json\/wp\/v2\/pages\/1868\/revisions\/3019"}],"up":[{"embeddable":true,"href":"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-json\/wp\/v2\/pages\/1804"}],"wp:attachment":[{"href":"https:\/\/rally-kumrovec.com\/2024\/arhiva\/wp-json\/wp\/v2\/media?parent=1868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}